{"id":1005,"name":"Etienne Gombert","url":"","description":"Apr\u00e8s avoir travaill\u00e9 plusieurs ann\u00e9es pour diff\u00e9rentes marques de cosm\u00e9tiques, j\u2019ai rejoint l\u2019\u00e9quipe FOREO anim\u00e9 par l\u2019envie de faire partie du monde de demain ! Attir\u00e9 depuis toujours par les nouvelles technologies, le bien-\u00eatre, la sant\u00e9, le soin de la peau, je suis \u00e9galement un grand fan de sport et notamment de fitness ainsi que de litt\u00e9rature contemporaine, car rien n\u2019est antinomique en ce monde ! Mon plaisir ultime : \u00e9couter des livres audio en faisant du sport\u2026","link":"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/","slug":"etienneg","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b035557bff1c2d9ac303ad4060f9dbca88a6d2729619cc319a26551b1611d0ff?s=24&d=mm&r=pg","48":"https:\/\/secure.gravatar.com\/avatar\/b035557bff1c2d9ac303ad4060f9dbca88a6d2729619cc319a26551b1611d0ff?s=48&d=mm&r=pg","96":"https:\/\/secure.gravatar.com\/avatar\/b035557bff1c2d9ac303ad4060f9dbca88a6d2729619cc319a26551b1611d0ff?s=96&d=mm&r=pg"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Etienne Gombert, Author at MYSA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Etienne Gombert, Author at MYSA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/\" \/>\n<meta property=\"og:site_name\" content=\"MYSA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/389f1391fd7b492e026428a497754326?s=500&d=mm&r=pg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/\",\"url\":\"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/\",\"name\":\"Etienne Gombert, Author at MYSA\",\"isPartOf\":{\"@id\":\"https:\/\/www.foreo.com\/fr\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"BLOG\",\"item\":\"https:\/\/www.foreo.com\/fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e9gorie pour Etienne Gombert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.foreo.com\/fr\/blog\/#website\",\"url\":\"https:\/\/www.foreo.com\/fr\/blog\/\",\"name\":\"MYSA\",\"description\":\"Le Blog de FOREO\",\"publisher\":{\"@id\":\"https:\/\/www.foreo.com\/fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.foreo.com\/fr\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.foreo.com\/fr\/blog\/#organization\",\"name\":\"MYSA de FOREO\",\"url\":\"https:\/\/www.foreo.com\/fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.foreo.com\/fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.foreo.com\/fr\/blog\/wp-content\/uploads\/2022\/02\/mysa-logo-w-quote-france-re\u0301seaux-sociaux.jpg\",\"contentUrl\":\"https:\/\/www.foreo.com\/fr\/blog\/wp-content\/uploads\/2022\/02\/mysa-logo-w-quote-france-re\u0301seaux-sociaux.jpg\",\"width\":2500,\"height\":1312,\"caption\":\"MYSA de FOREO\"},\"image\":{\"@id\":\"https:\/\/www.foreo.com\/fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FOREOFrance\/\",\"https:\/\/www.instagram.com\/foreo_france\/\",\"https:\/\/www.youtube.com\/playlist?list=PLvV6UceMUecxDg_AKB3YXDjmkeASETQcw\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.foreo.com\/fr\/blog\/#\/schema\/person\/314cc6a1a87f37bcd46eb3963b1aef82\",\"name\":\"Etienne Gombert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.foreo.com\/fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b035557bff1c2d9ac303ad4060f9dbca88a6d2729619cc319a26551b1611d0ff?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b035557bff1c2d9ac303ad4060f9dbca88a6d2729619cc319a26551b1611d0ff?s=96&d=mm&r=pg\",\"caption\":\"Etienne Gombert\"},\"description\":\"Apr\u00e8s avoir travaill\u00e9 plusieurs ann\u00e9es pour diff\u00e9rentes marques de cosm\u00e9tiques, j\u2019ai rejoint l\u2019\u00e9quipe FOREO anim\u00e9 par l\u2019envie de faire partie du monde de demain ! Attir\u00e9 depuis toujours par les nouvelles technologies, le bien-\u00eatre, la sant\u00e9, le soin de la peau, je suis \u00e9galement un grand fan de sport et notamment de fitness ainsi que de litt\u00e9rature contemporaine, car rien n\u2019est antinomique en ce monde ! Mon plaisir ultime : \u00e9couter des livres audio en faisant du sport\u2026\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Etienne Gombert, Author at MYSA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/","og_locale":"fr_FR","og_type":"profile","og_title":"Etienne Gombert, Author at MYSA","og_url":"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/","og_site_name":"MYSA","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/389f1391fd7b492e026428a497754326?s=500&d=mm&r=pg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/","url":"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/","name":"Etienne Gombert, Author at MYSA","isPartOf":{"@id":"https:\/\/www.foreo.com\/fr\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"BLOG","item":"https:\/\/www.foreo.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e9gorie pour Etienne Gombert"}]},{"@type":"WebSite","@id":"https:\/\/www.foreo.com\/fr\/blog\/#website","url":"https:\/\/www.foreo.com\/fr\/blog\/","name":"MYSA","description":"Le Blog de FOREO","publisher":{"@id":"https:\/\/www.foreo.com\/fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.foreo.com\/fr\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.foreo.com\/fr\/blog\/#organization","name":"MYSA de FOREO","url":"https:\/\/www.foreo.com\/fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.foreo.com\/fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.foreo.com\/fr\/blog\/wp-content\/uploads\/2022\/02\/mysa-logo-w-quote-france-re\u0301seaux-sociaux.jpg","contentUrl":"https:\/\/www.foreo.com\/fr\/blog\/wp-content\/uploads\/2022\/02\/mysa-logo-w-quote-france-re\u0301seaux-sociaux.jpg","width":2500,"height":1312,"caption":"MYSA de FOREO"},"image":{"@id":"https:\/\/www.foreo.com\/fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FOREOFrance\/","https:\/\/www.instagram.com\/foreo_france\/","https:\/\/www.youtube.com\/playlist?list=PLvV6UceMUecxDg_AKB3YXDjmkeASETQcw"]},{"@type":"Person","@id":"https:\/\/www.foreo.com\/fr\/blog\/#\/schema\/person\/314cc6a1a87f37bcd46eb3963b1aef82","name":"Etienne Gombert","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.foreo.com\/fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b035557bff1c2d9ac303ad4060f9dbca88a6d2729619cc319a26551b1611d0ff?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b035557bff1c2d9ac303ad4060f9dbca88a6d2729619cc319a26551b1611d0ff?s=96&d=mm&r=pg","caption":"Etienne Gombert"},"description":"Apr\u00e8s avoir travaill\u00e9 plusieurs ann\u00e9es pour diff\u00e9rentes marques de cosm\u00e9tiques, j\u2019ai rejoint l\u2019\u00e9quipe FOREO anim\u00e9 par l\u2019envie de faire partie du monde de demain ! Attir\u00e9 depuis toujours par les nouvelles technologies, le bien-\u00eatre, la sant\u00e9, le soin de la peau, je suis \u00e9galement un grand fan de sport et notamment de fitness ainsi que de litt\u00e9rature contemporaine, car rien n\u2019est antinomique en ce monde ! Mon plaisir ultime : \u00e9couter des livres audio en faisant du sport\u2026","mainEntityOfPage":{"@id":"https:\/\/www.foreo.com\/fr\/blog\/author\/etienneg\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.foreo.com\/fr\/blog\/wp-json\/wp\/v2\/users\/1005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.foreo.com\/fr\/blog\/wp-json\/wp\/v2\/users"}]}}